{"id":4505,"date":"2018-06-07T05:42:03","date_gmt":"2018-06-07T04:42:03","guid":{"rendered":"https:\/\/sinapak.com\/contatti\/"},"modified":"2020-11-03T17:42:03","modified_gmt":"2020-11-03T16:42:03","slug":"contacts","status":"publish","type":"page","link":"https:\/\/sinapak.com\/en\/contacts\/","title":{"rendered":"Contacts"},"content":{"rendered":"<p>[vc_row tm_bgcolor=&#8221;white&#8221; tm_bgimagefixed=&#8221;&#8221; break_in_responsive=&#8221;1200&#8243; full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1535171979828{padding-top: 90px !important;}&#8221; el_class=&#8221;padding-top-0px-1200 padding-bottom-0px-1200&#8243;][vc_column tm_bgcolor=&#8221;darkgrey&#8221; width=&#8221;3\/4&#8243;][vc_row_inner break_in_responsive=&#8221;991&#8243; tm_shadow=&#8221;yes&#8221; css=&#8221;.vc_custom_1537008633495{padding-top: 50px !important;padding-right: 50px !important;padding-bottom: 30px !important;padding-left: 40px !important;}&#8221; tm_responsive_css=&#8221;84833920|colbreak_no|||||||||colbreak_no|||||||||colbreak_no||||||15px||15px||colbreak_no|||||||||&#8221;][vc_column_inner width=&#8221;5\/6&#8243; css=&#8221;.vc_custom_1536909373028{padding-right: 90px !important;}&#8221; tm_responsive_css=&#8221;23362522|colbreak_no|||||||||colbreak_no||||||20px|||colbreak_no||||||||||colbreak_no|||||||||&#8221;]<div class=\"tm-element-heading-wrapper tm-heading-inner tm-element-align-left tm-seperator-solid tm-heading-style-vertical  vc_custom_1604412475260\"><section class=\"tm-vc_cta3-container\"><div class=\"tm-vc_general tm-vc_cta3 tm-cta3-only tm-vc_cta3-style-classic tm-vc_cta3-shape-rounded tm-vc_cta3-align-left tm-vc_cta3-color-transparent tm-vc_cta3-icon-size-md tm-vc_cta3-actions-no tm-cta3-without-desc\"><div class=\"tm-vc_cta3_content-container\"><div class=\"tm-vc_cta3-content\"><header class=\"tm-vc_cta3-content-header tm-wrap\"><div class=\"tm-vc_cta3-headers tm-wrap-cell\"><h2 class=\"tm-custom-heading \" >Write to us<\/h2>\n<h4 class=\"tm-custom-heading \" >To receive any information: we will be glad to answer you as soon as we can!<\/h4>\n<\/div><div class=\"heading-seperator\"><span><\/span><\/div><\/header><\/div><\/div><\/div><\/section><\/div> <!-- .tm-element-heading-wrapper container --> <div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f4529-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/4505\/#wpcf7-f4529-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"4529\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f4529-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"tm-contactform tm-commonform\">\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<div class=\"field-group\"><i class=\"ti-user\"><\/i><span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" \/><\/span><\/div><\/div><\/div>\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<div class=\"field-group\"><i class=\"ti-email\"><\/i><span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" \/><\/span><\/div><\/div><\/div>\n<div class=\"row\">\n<div class=\"col-xs-12\">\n<div class=\"field-group\"><i class=\"ti-mobile\"><\/i><span class=\"wpcf7-form-control-wrap your-phoneno\"><input type=\"text\" name=\"your-phoneno\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" \/><\/span><\/div><\/div><\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-sm-12\">\n<div class=\"field-group\"><i class=\"ti-comment\"><\/i><span class=\"wpcf7-form-control-wrap message\"><textarea name=\"message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\"><\/textarea><\/span><\/div><\/div><\/div>\n<div class=\"row\">\n<div class=\"col-xs-12 col-sm-12 tm-book-submitbt\"><input type=\"submit\" value=\"Send\" class=\"wpcf7-form-control wpcf7-submit tm-vc_general tm-vc_btn3 tm-vc_btn3-style-outline tm-vc_btn3-size-md tm-vc_btn3-color-white\" \/><\/div><\/div>\n<\/div>\n<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column tm_textcolor=&#8221;white&#8221; width=&#8221;1\/4&#8243; el_class=&#8221;padding-leftright-0px-1200&#8243;][vc_row_inner el_class=&#8221;tm-bgcolor-skincolor&#8221; css=&#8221;.vc_custom_1537249764850{margin-top: 124px !important;margin-left: -215px !important;padding-top: 85px !important;padding-right: 30px !important;padding-bottom: 63px !important;padding-left: 35px !important;}&#8221; tm_responsive_css=&#8221;53547819|colbreak_no|0px|0px|0px|0px|||||colbreak_no|||||||||colbreak_no||||||30px||30px||colbreak_no|||||||||&#8221;][vc_column_inner]<h2 style=\"text-align:left;\" class=\"tm-custom-heading vc_custom_1604398695210\" >Contact us<\/h2>\n<div class=\"tm-sbox tm-sbox-iconalign-left-spacing none tm-sbox-bgcolor-transparent tm-bgcolor-transparent tm-sbox-textcolor- tm-textcolor- tm-sbox-isize-md tm-sbox-isize-md tm-sbox-istyle-none vc_custom_1604398722024 tm-sbox-both-headings ttm-sbox-iconpadding-0px\"><section class=\"tm-vc_cta3-container\"><div class=\"tm-vc_general tm-vc_cta3 tm-vc_cta3-align-left tm-vc_cta3-icon-size-md tm-vc_cta3-icons-left tm-vc_cta3-actions-no\"><div class=\"tm-vc_cta3-icons tm-wrap-cell\"><div class=\"tm-vc_icon_element tm-vc_icon_element-outer tm-vc_icon_element-align-left \"><div class=\"tm-vc_icon_element-inner  tm-vc_icon_element-color-white tm-vc_icon_element-size-md tm-vc_icon_element-style-none tm-vc_icon_element-background-color-grey\" ><span class=\"tm-vc_icon_element-icon themifyicon ti-mobile\" ><\/span><\/div><\/div><\/div><div class=\"tm-vc_cta3_content-container\"><div class=\"tm-vc_cta3-content\"><div class=\"tm-vc_cta3-content-header tm-wrap\"><div class=\"tm-vc_cta3-headers tm-wrap-cell\"><h2 style=\"font-size:22px;line-height:27px;\" class=\"tm-custom-heading \" >Phone - Fax<\/h2>\n<h4 style=\"font-size:16px;line-height:22px;\" class=\"tm-custom-heading \" >Tel. +39.0385.277041 - Fax. +39.0385.277040<\/h4>\n<\/div><\/div><\/div><div class=\"tm-cta3-desc-btn-wrapper\"><div class=\"tm-cta3-description\"><\/div><\/div><\/div><\/div><\/section><\/div><div class=\"tm-sbox tm-sbox-iconalign-left-spacing none tm-sbox-bgcolor-transparent tm-bgcolor-transparent tm-sbox-textcolor- tm-textcolor- tm-sbox-isize-md tm-sbox-isize-md tm-sbox-istyle-none vc_custom_1604398747565 tm-sbox-both-headings ttm-sbox-iconpadding-0px\"><section class=\"tm-vc_cta3-container\"><div class=\"tm-vc_general tm-vc_cta3 tm-vc_cta3-align-left tm-vc_cta3-icon-size-md tm-vc_cta3-icons-left tm-vc_cta3-actions-no\"><div class=\"tm-vc_cta3-icons tm-wrap-cell\"><div class=\"tm-vc_icon_element tm-vc_icon_element-outer tm-vc_icon_element-align-left \"><div class=\"tm-vc_icon_element-inner  tm-vc_icon_element-color-white tm-vc_icon_element-size-md tm-vc_icon_element-style-none tm-vc_icon_element-background-color-grey\" ><span class=\"tm-vc_icon_element-icon themifyicon ti-email\" ><\/span><\/div><\/div><\/div><div class=\"tm-vc_cta3_content-container\"><div class=\"tm-vc_cta3-content\"><div class=\"tm-vc_cta3-content-header tm-wrap\"><div class=\"tm-vc_cta3-headers tm-wrap-cell\"><h2 style=\"font-size:22px;line-height:27px;\" class=\"tm-custom-heading \" >E-mail<\/h2>\n<h4 style=\"font-size:16px;line-height:22px;\" class=\"tm-custom-heading \" >info@sinapak.com<\/h4>\n<\/div><\/div><\/div><div class=\"tm-cta3-desc-btn-wrapper\"><div class=\"tm-cta3-description\"><\/div><\/div><\/div><\/div><\/section><\/div><div class=\"tm-sbox tm-sbox-iconalign-left-spacing none tm-sbox-bgcolor-transparent tm-bgcolor-transparent tm-sbox-textcolor- tm-textcolor- tm-sbox-isize-md tm-sbox-isize-md tm-sbox-istyle-none vc_custom_1604398772216 tm-sbox-both-headings ttm-sbox-iconpadding-0px\"><section class=\"tm-vc_cta3-container\"><div class=\"tm-vc_general tm-vc_cta3 tm-vc_cta3-align-left tm-vc_cta3-icon-size-md tm-vc_cta3-icons-left tm-vc_cta3-actions-no\"><div class=\"tm-vc_cta3-icons tm-wrap-cell\"><div class=\"tm-vc_icon_element tm-vc_icon_element-outer tm-vc_icon_element-align-left \"><div class=\"tm-vc_icon_element-inner  tm-vc_icon_element-color-white tm-vc_icon_element-size-md tm-vc_icon_element-style-none tm-vc_icon_element-background-color-grey\" ><span class=\"tm-vc_icon_element-icon themifyicon ti-location-pin\" ><\/span><\/div><\/div><\/div><div class=\"tm-vc_cta3_content-container\"><div class=\"tm-vc_cta3-content\"><div class=\"tm-vc_cta3-content-header tm-wrap\"><div class=\"tm-vc_cta3-headers tm-wrap-cell\"><h2 style=\"font-size:22px;line-height:27px;\" class=\"tm-custom-heading \" >Address<\/h2>\n<h4 style=\"font-size:16px;line-height:22px;\" class=\"tm-custom-heading \" >Via Industria e Artigianato, 7 - 27049 Stradella (Pavia) - Italy<\/h4>\n<\/div><\/div><\/div><div class=\"tm-cta3-desc-btn-wrapper\"><div class=\"tm-cta3-description\"><\/div><\/div><\/div><\/div><\/section><\/div>[vc_column_text css=&#8221;.vc_custom_1529729523621{padding-left: 12px !important;}&#8221;]<div class=\"themetechmount-social-links-wrapper\"><ul class=\"social-icons\"><li class=\"tm-social-facebook\"><a class=\" tooltip-top\" target=\"_blank\" href=\"https:\/\/www.facebook.com\/SINAPAKSRL\" data-tooltip=\"Facebook\"><i class=\"tm-tectxon-icon-facebook\"><\/i><\/a><\/li>\n<li class=\"tm-social-instagram\"><a class=\" tooltip-top\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/sinapaksrl\/?hl=it\" data-tooltip=\"Instagram\"><i class=\"tm-tectxon-icon-instagram\"><\/i><\/a><\/li>\n<\/ul><\/div>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row tm_bgimagefixed=&#8221;&#8221; full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1528363766947{margin-bottom: 0px !important;padding-top: 0px !important;padding-bottom: 0px !important;}&#8221;][vc_column][vc_gmaps link=&#8221;#E-8_JTNDaWZyYW1lJTIwc3JjJTNEJTIyaHR0cHMlM0ElMkYlMkZ3d3cuZ29vZ2xlLmNvbSUyRm1hcHMlMkZlbWJlZCUzRnBiJTNEJTIxMW0xOCUyMTFtMTIlMjExbTMlMjExZDI4MTYuNzUwMjgzOTAwMzI1JTIxMmQ5LjI3OTI4NDMxNTc1NzYwNCUyMTNkNDUuMDkwODU2NzY2Mjk3NjA1JTIxMm0zJTIxMWYwJTIxMmYwJTIxM2YwJTIxM20yJTIxMWkxMDI0JTIxMmk3NjglMjE0ZjEzLjElMjEzbTMlMjExbTIlMjExczB4NDc4NzJkOTdlM2ZkZWY1MSUyNTNBMHg2ZGJhYmU5MGVjMTJhMjQ0JTIxMnNTSU5BUEFLJTI1MjBTUkwlMjE1ZTAlMjEzbTIlMjExc2l0JTIxMnNpdCUyMTR2MTYwMDkzOTcxMTU2NiUyMTVtMiUyMTFzaXQlMjEyc2l0JTIyJTIwd2lkdGglM0QlMjI2MDAlMjIlMjBoZWlnaHQlM0QlMjI0NTAlMjIlMjBmcmFtZWJvcmRlciUzRCUyMjAlMjIlMjBzdHlsZSUzRCUyMmJvcmRlciUzQTAlM0IlMjIlMjBhbGxvd2Z1bGxzY3JlZW4lM0QlMjIlMjIlMjBhcmlhLWhpZGRlbiUzRCUyMmZhbHNlJTIyJTIwdGFiaW5kZXglM0QlMjIwJTIyJTNFJTNDJTJGaWZyYW1lJTNF&#8221; size=&#8221;400&#8243; css=&#8221;.vc_custom_1600939794770{margin-bottom: 0px !important;}&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row tm_bgcolor=&#8221;white&#8221; tm_bgimagefixed=&#8221;&#8221; break_in_responsive=&#8221;1200&#8243; full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1535171979828{padding-top: 90px !important;}&#8221; el_class=&#8221;padding-top-0px-1200 padding-bottom-0px-1200&#8243;][vc_column tm_bgcolor=&#8221;darkgrey&#8221; width=&#8221;3\/4&#8243;][vc_row_inner break_in_responsive=&#8221;991&#8243; tm_shadow=&#8221;yes&#8221; css=&#8221;.vc_custom_1537008633495{padding-top: 50px !important;padding-right: 50px !important;padding-bottom: 30px !important;padding-left: 40px !important;}&#8221; tm_responsive_css=&#8221;84833920|colbreak_no|||||||||colbreak_no|||||||||colbreak_no||||||15px||15px||colbreak_no|||||||||&#8221;][vc_column_inner width=&#8221;5\/6&#8243; css=&#8221;.vc_custom_1536909373028{padding-right: 90px !important;}&#8221; tm_responsive_css=&#8221;23362522|colbreak_no|||||||||colbreak_no||||||20px|||colbreak_no||||||||||colbreak_no|||||||||&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column tm_textcolor=&#8221;white&#8221; width=&#8221;1\/4&#8243; el_class=&#8221;padding-leftright-0px-1200&#8243;][vc_row_inner el_class=&#8221;tm-bgcolor-skincolor&#8221; css=&#8221;.vc_custom_1537249764850{margin-top: 124px !important;margin-left: -215px !important;padding-top: 85px !important;padding-right: 30px !important;padding-bottom: 63px !important;padding-left: 35px !important;}&#8221; tm_responsive_css=&#8221;53547819|colbreak_no|0px|0px|0px|0px|||||colbreak_no|||||||||colbreak_no||||||30px||30px||colbreak_no|||||||||&#8221;][vc_column_inner][vc_column_text css=&#8221;.vc_custom_1529729523621{padding-left: 12px !important;}&#8221;][\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row tm_bgimagefixed=&#8221;&#8221; full_width=&#8221;stretch_row_content_no_spaces&#8221; css=&#8221;.vc_custom_1528363766947{margin-bottom: 0px &hellip; <a href=\"https:\/\/sinapak.com\/en\/contacts\/\" class=\"more-link\">Continue reading <span class=\"screen-reader-text\">Contacts<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4505","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sinapak.com\/en\/wp-json\/wp\/v2\/pages\/4505\/"}],"collection":[{"href":"https:\/\/sinapak.com\/en\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/sinapak.com\/en\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/sinapak.com\/en\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/sinapak.com\/en\/wp-json\/wp\/v2\/comments\/?post=4505"}],"version-history":[{"count":3,"href":"https:\/\/sinapak.com\/en\/wp-json\/wp\/v2\/pages\/4505\/revisions\/"}],"predecessor-version":[{"id":4530,"href":"https:\/\/sinapak.com\/en\/wp-json\/wp\/v2\/pages\/4505\/revisions\/4530\/"}],"wp:attachment":[{"href":"https:\/\/sinapak.com\/en\/wp-json\/wp\/v2\/media\/?parent=4505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}